{"id":64,"date":"2024-03-01T01:44:08","date_gmt":"2024-02-29T16:44:08","guid":{"rendered":"https:\/\/chiba-pt.or.jp\/wp\/pt\/?page_id=64"},"modified":"2026-02-13T21:37:44","modified_gmt":"2026-02-13T12:37:44","slug":"lifelong_requirements","status":"publish","type":"page","link":"https:\/\/chiba-pt.or.jp\/pt\/lifelong\/lifelong_requirements\/","title":{"rendered":"\u58eb\u4f1a\u627f\u8a8d\u8981\u4ef6"},"content":{"rendered":"\n<p>\u4f1a\u54e1\u6240\u5c5e\u65bd\u8a2d\u3067\u958b\u50ac\u3059\u308b\u75c7\u4f8b\u691c\u8a0e\u4f1a\u3001\u66f4\u65b0\u7814\u4fee\u4f1a\u306f\u3001\u4ee5\u4e0b\u306e\u8981\u4ef6\u306b\u57fa\u3065\u304d\u3001\u5354\u4f1a\u30de\u30a4\u30da\u30fc\u30b8\u3088\u308a\u7533\u8acb\u3092\u884c\u3063\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4f1a\u54e1\u6240\u5c5e\u65bd\u8a2d\u3067\u958b\u50ac\u3059\u308b\u75c7\u4f8b\u691c\u8a0e\u4f1a\u3001\u66f4\u65b0\u7814\u4fee\u4f1a\u306f\u3001\u4ee5\u4e0b\u306e\u8981\u4ef6\u306b\u57fa\u3065\u304d\u3001\u5354\u4f1a\u30de\u30a4\u30da\u30fc\u30b8\u3088\u308a\u7533\u8acb\u3092\u884c\u3063\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":29,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"aioseo_notices":[],"acf":[],"_links":{"self":[{"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/pages\/64"}],"collection":[{"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":16,"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/pages\/64\/revisions"}],"predecessor-version":[{"id":1672,"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/pages\/64\/revisions\/1672"}],"up":[{"embeddable":true,"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/pages\/29"}],"wp:attachment":[{"href":"https:\/\/chiba-pt.or.jp\/pt\/wp-json\/wp\/v2\/media?parent=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}